{"id":338,"date":"2017-11-06T18:35:53","date_gmt":"2017-11-06T18:35:53","guid":{"rendered":"https:\/\/clubztutoring.com\/nickp\/v2\/?page_id=338"},"modified":"2017-11-06T18:35:53","modified_gmt":"2017-11-06T18:35:53","slug":"in-the-news","status":"publish","type":"page","link":"https:\/\/clubztutoring.com\/eden-prairie\/in-the-news\/","title":{"rendered":"In the News"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":44,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-338","page","type-page","status-publish","hentry","wpautop"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>In the News -Eden Prairie, MN<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/clubztutoring.com\/eden-prairie\/in-the-news\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"In the News -Eden Prairie, MN\" \/>\n<meta property=\"og:url\" content=\"https:\/\/clubztutoring.com\/eden-prairie\/in-the-news\/\" \/>\n<meta property=\"og:site_name\" content=\"Eden Prairie, MN\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/clubztutoring.com\\\/eden-prairie\\\/in-the-news\\\/\",\"url\":\"https:\\\/\\\/clubztutoring.com\\\/eden-prairie\\\/in-the-news\\\/\",\"name\":\"In the News -Eden Prairie, MN\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/clubztutoring.com\\\/eden-prairie\\\/#website\"},\"datePublished\":\"2017-11-06T18:35:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/clubztutoring.com\\\/eden-prairie\\\/in-the-news\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/clubztutoring.com\\\/eden-prairie\\\/in-the-news\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/clubztutoring.com\\\/eden-prairie\\\/in-the-news\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/clubztutoring.com\\\/eden-prairie\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"In the News\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/clubztutoring.com\\\/eden-prairie\\\/#website\",\"url\":\"https:\\\/\\\/clubztutoring.com\\\/eden-prairie\\\/\",\"name\":\"Eden Prairie, MN\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/clubztutoring.com\\\/eden-prairie\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"In the News -Eden Prairie, MN","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/clubztutoring.com\/eden-prairie\/in-the-news\/","og_locale":"en_US","og_type":"article","og_title":"In the News -Eden Prairie, MN","og_url":"https:\/\/clubztutoring.com\/eden-prairie\/in-the-news\/","og_site_name":"Eden Prairie, MN","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/clubztutoring.com\/eden-prairie\/in-the-news\/","url":"https:\/\/clubztutoring.com\/eden-prairie\/in-the-news\/","name":"In the News -Eden Prairie, MN","isPartOf":{"@id":"https:\/\/clubztutoring.com\/eden-prairie\/#website"},"datePublished":"2017-11-06T18:35:53+00:00","breadcrumb":{"@id":"https:\/\/clubztutoring.com\/eden-prairie\/in-the-news\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/clubztutoring.com\/eden-prairie\/in-the-news\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/clubztutoring.com\/eden-prairie\/in-the-news\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/clubztutoring.com\/eden-prairie\/"},{"@type":"ListItem","position":2,"name":"In the News"}]},{"@type":"WebSite","@id":"https:\/\/clubztutoring.com\/eden-prairie\/#website","url":"https:\/\/clubztutoring.com\/eden-prairie\/","name":"Eden Prairie, MN","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/clubztutoring.com\/eden-prairie\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/clubztutoring.com\/eden-prairie\/wp-json\/wp\/v2\/pages\/338","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/clubztutoring.com\/eden-prairie\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/clubztutoring.com\/eden-prairie\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/clubztutoring.com\/eden-prairie\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/clubztutoring.com\/eden-prairie\/wp-json\/wp\/v2\/comments?post=338"}],"version-history":[{"count":0,"href":"https:\/\/clubztutoring.com\/eden-prairie\/wp-json\/wp\/v2\/pages\/338\/revisions"}],"wp:attachment":[{"href":"https:\/\/clubztutoring.com\/eden-prairie\/wp-json\/wp\/v2\/media?parent=338"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}